{"id":2793,"date":"2025-05-13T14:35:00","date_gmt":"2025-05-13T14:35:00","guid":{"rendered":"https:\/\/windfloat-atlantic.com\/?p=2793"},"modified":"2026-03-02T14:41:41","modified_gmt":"2026-03-02T14:41:41","slug":"ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic","status":"publish","type":"post","link":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/","title":{"rendered":"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic"},"content":{"rendered":"\n<ul class=\"wp-block-list\">\n<li><em>O WindFloat Atlantic (WFA) superou as estimativas de produ\u00e7\u00e3o de energia ao longo dos seus cinco anos de opera\u00e7\u00e3o, com uma produ\u00e7\u00e3o total acumulada de 345&nbsp;GWh, fornecendo energia limpa ao equivalente a 25.000 lares portugueses por ano.<\/em>&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><em>O sucesso do projeto vai al\u00e9m da mera inova\u00e7\u00e3o tecnol\u00f3gica, representando um legado enraizado em um forte compromisso com a comunidade local, as gera\u00e7\u00f5es presentes e futuras da for\u00e7a de trabalho, a ind\u00fastria da pesca e a gest\u00e3o ambiental. Demonstra que a OW, com sua tecnologia, est\u00e1 pronta para a escalabilidade comercial em Portugal.<\/em>&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>14 de Maio, Viana do Castelo.&nbsp;<\/strong>Ocean Winds \u2014 uma&nbsp;joint&nbsp;venture 50:50 entre a EDP Renov\u00e1veis e a ENGIE, e a principal desenvolvedora do projeto WindFloat Atlantic de 25 MW, o primeiro parque e\u00f3lico offshore semi-submers\u00edvel flutuante do mundo, localizado a aproximadamente 20 quil\u00f4metros da costa de Viana do Castelo \u2014 celebra o quinto anivers\u00e1rio das opera\u00e7\u00f5es do WindFloat Atlantic.&nbsp;<\/p>\n\n\n\n<p>A ocasi\u00e3o \u00e9 marcada por uma s\u00e9rie de iniciativas, incluindo o descerramento de uma placa comemorativa na base de Opera\u00e7\u00f5es e Manuten\u00e7\u00e3o (O&amp;M), com a presen\u00e7a do Presidente da C\u00e2mara Municipal de Viana do Castelo, Dr. Lu\u00eds Nobre, e do CEO da Ocean Winds, Craig Windram. A celebra\u00e7\u00e3o tamb\u00e9m inclui um jantar institucional com cerca de 150 convidados a bordo do navio da Marinha Portuguesa NRP Sagres, atracado em Viana do Castelo. Os convidados incluem representantes da OW, EDPR, ENGIE, parceiros do projeto, a Rep\u00fablica Portuguesa, administra\u00e7\u00f5es central e regional, autoridades locais, associa\u00e7\u00f5es do setor, academia e comunidades locais. O evento oferece uma excelente oportunidade para celebrar as conquistas do projeto, expressar gratid\u00e3o pela dedica\u00e7\u00e3o e compromisso demonstrados, e destacar as oportunidades para a energia e\u00f3lica offshore em Portugal.&nbsp;<\/p>\n\n\n\n<p>Adicionalmente, est\u00e1 dispon\u00edvel um relat\u00f3rio sobre o impacto positivo do projeto ao longo dos \u00faltimos cinco anos \u2014 Cinco Anos a Produzir Energia Renov\u00e1vel no WindFloat Atlantic: Vivendo a Energia E\u00f3lica Offshore Flutuante \u2014 que destaca os seus impactos econ\u00f3micos, sociais e ambientais, n\u00e3o apenas em Portugal, mas tamb\u00e9m a n\u00edvel global. O relat\u00f3rio abrange todo o trabalho realizado at\u00e9 \u00e0 data, iniciado h\u00e1 mais de 15 anos com o prot\u00f3tipo WindFloat1, at\u00e9 aos dias de hoje, com um projeto que supera as expectativas de produ\u00e7\u00e3o anual, alcan\u00e7ando uma produ\u00e7\u00e3o total acumulada de 345,2&nbsp;GWh.&nbsp;<\/p>\n\n\n\n<p>Neste contexto, destacam-se cinco \u00e1reas-chave onde o WindFloat Atlantic gerou valor e impulsionou a evolu\u00e7\u00e3o do setor:&nbsp;<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Fortalecimento da cadeia de fornecimento europeia: Empregos, compet\u00eancias e experi\u00eancia transfer\u00edvel<\/em><\/strong><em>: Com um investimento de 125 milh\u00f5es de euros e a cria\u00e7\u00e3o de 1.500 empregos indiretos, o WindFloat Atlantic tem apoiado uma cadeia de fornecimento europeia resiliente, trabalhando em estreita colabora\u00e7\u00e3o com parceiros nacionais e internacionais, demonstrando o potencial de sucesso a longo prazo do setor de energia e\u00f3lica offshore flutuante.<\/em>&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Fornecendo energia limpa e eficiente \u00e0s resid\u00eancias portuguesas<\/em><\/strong><em>: Comprometidos em fornecer energia limpa e descarbonizada atrav\u00e9s de opera\u00e7\u00f5es e manuten\u00e7\u00e3o (O&amp;M) seguras, fi\u00e1veis e de alta qualidade, apoiando a transi\u00e7\u00e3o energ\u00e9tica global.<\/em>&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Trabalhando com as comunidades locais para um impacto positivo<\/em><\/strong><em>: O WindFloat Atlantic demonstra que a energia e\u00f3lica offshore e as comunidades locais podem prosperar juntas \u2014 impulsionadas pela colabora\u00e7\u00e3o e um compromisso compartilhado, atrav\u00e9s do desenvolvimento de programas educativos locais (300 estudantes de Viana do Castelo j\u00e1 participaram no nosso programa educativo &#8220;Wind Experts&#8221;).<\/em>&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>Coexist\u00eancia com o ambiente: Proteger e valorizar<\/em><\/strong><em>: Atrav\u00e9s deste compromisso, \u00e9 assegurado que o desenvolvimento e a opera\u00e7\u00e3o do parque e\u00f3lico sejam realizados em harmonia com o seu ecossistema (atividades de monitoriza\u00e7\u00e3o t\u00eam sido frequentemente realizadas, permitindo a identifica\u00e7\u00e3o de mais de 270 esp\u00e9cies, demonstrando que o recurso pesqueiro n\u00e3o diminuiu).<\/em>&nbsp;<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><em>De Portugal para o Mundo<\/em><\/strong><em>: O WindFloat Atlantic, com Portugal como base, provou que a energia e\u00f3lica offshore flutuante est\u00e1 pronta para projetos comerciais em grande escala em Portugal e ajudou a desbloquear seu potencial global, j\u00e1 sendo aplicada no portf\u00f3lio comercial flutuante da OW.<\/em>&nbsp;<\/li>\n<\/ul>\n\n\n\n<p><strong>Jos\u00e9 Miguel Pinheiro, Diretor da OW para a Ib\u00e9ria,&nbsp;<\/strong>referiu,&nbsp;<em>&#8220;Estamos orgulhosos por ver que o nosso projeto celebra cinco anos de opera\u00e7\u00e3o bem-sucedida, acumulando um impacto cada vez mais positivo que vai al\u00e9m da produ\u00e7\u00e3o de energia limpa. Na OW, estamos profundamente comprometidos em garantir que o nosso projeto tenha um impacto completo \u2014 desde o desenvolvimento do projeto at\u00e9 aos dias de hoje \u2014 promovendo a cadeia de fornecedores, colaborando com a comunidade, protegendo o ambiente e demonstrando ao mundo que o WindFloat \u00e9 um exemplo de sucesso, j\u00e1 replicado comercialmente noutros pa\u00edses, e que estamos prontos para dar esse passo tamb\u00e9m em Portugal.&#8221;<\/em>&nbsp;<\/p>\n\n\n\n<p><strong>O Presidente da C\u00e2mara Municipal de Viana do Castelo, Dr. Lu\u00eds Nobre,<\/strong>&nbsp;declarou,&nbsp;<em>\u201cO Munic\u00edpio de Viana do Castelo congratula-se com a celebra\u00e7\u00e3o do 5.\u00ba anivers\u00e1rio do WindFloat Atlantic, um projeto pioneiro e inovador que se afirmou como uma refer\u00eancia global na \u00e1rea da energia e\u00f3lica offshore. Ter esta infraestrutura de excel\u00eancia instalada ao largo da nossa costa \u00e9 motivo de grande orgulho, pois refor\u00e7a a posi\u00e7\u00e3o de Viana do Castelo e da empresa OW na linha da frente da tecnologia e da sustentabilidade energ\u00e9tica a n\u00edvel mundial. \u00c9, sem d\u00favida, um privil\u00e9gio integrar esta trajet\u00f3ria de vanguarda e progresso.\u201d<\/em>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_097-1024x683.jpg\" alt=\"\" class=\"wp-image-2861\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_097-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_097-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_097-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_097-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_097-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2859\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_049-1024x683.jpg\" alt=\"\" class=\"wp-image-2859\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_049-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_049-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_049-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_049-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_049-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2847\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__072-1024x683.jpg\" alt=\"\" class=\"wp-image-2847\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__072-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__072-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__072-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__072-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__072-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2858\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_081-1024x683.jpg\" alt=\"\" class=\"wp-image-2858\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_081-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_081-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_081-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_081-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_081-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2856\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_158-1024x683.jpg\" alt=\"\" class=\"wp-image-2856\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_158-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_158-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_158-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_158-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_158-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2857\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_180-1024x683.jpg\" alt=\"\" class=\"wp-image-2857\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_180-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_180-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_180-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_180-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_180-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2860\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_174-1024x683.jpg\" alt=\"\" class=\"wp-image-2860\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_174-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_174-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_174-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_174-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_174-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2845\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__164-1024x683.jpg\" alt=\"\" class=\"wp-image-2845\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__164-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__164-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__164-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__164-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/090525OceanWinds__164-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"2855\" src=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_121-1024x683.jpg\" alt=\"\" class=\"wp-image-2855\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_121-1024x683.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_121-300x200.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_121-768x512.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_121-1536x1024.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2025\/05\/130502025windfloat_121-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Celebrating five years of WindFloat Atlantic! \ud83c\udf89\u200b\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/e-Pxdy4NS9I?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>14 de Maio, Viana do Castelo.&nbsp;Ocean Winds \u2014 uma&nbsp;joint&nbsp;venture 50:50 entre a EDP Renov\u00e1veis e a ENGIE, e a principal desenvolvedora do projeto WindFloat Atlantic de 25 MW, o primeiro parque e\u00f3lico offshore semi-submers\u00edvel flutuante do mundo, localizado a aproximadamente 20 quil\u00f4metros da costa de Viana do Castelo \u2014 celebra o quinto anivers\u00e1rio das opera\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":104,"featured_media":2794,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-2793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic | Windfloat Atlantic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic | Windfloat Atlantic\" \/>\n<meta property=\"og:description\" content=\"14 de Maio, Viana do Castelo.&nbsp;Ocean Winds \u2014 uma&nbsp;joint&nbsp;venture 50:50 entre a EDP Renov\u00e1veis e a ENGIE, e a principal desenvolvedora do projeto WindFloat Atlantic de 25 MW, o primeiro parque e\u00f3lico offshore semi-submers\u00edvel flutuante do mundo, localizado a aproximadamente 20 quil\u00f4metros da costa de Viana do Castelo \u2014 celebra o quinto anivers\u00e1rio das opera\u00e7\u00f5es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/\" \/>\n<meta property=\"og:site_name\" content=\"Windfloat Atlantic\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-13T14:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T14:41:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2026\/02\/090525OceanWinds__127-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"claudia.barreiro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"claudia.barreiro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/\"},\"author\":{\"name\":\"claudia.barreiro\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/person\\\/def3ccdd491df4212cdb4b414f0134fb\"},\"headline\":\"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic\",\"datePublished\":\"2025-05-13T14:35:00+00:00\",\"dateModified\":\"2026-03-02T14:41:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/\"},\"wordCount\":957,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/090525OceanWinds__127-scaled.jpg\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/\",\"name\":\"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic | Windfloat Atlantic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/090525OceanWinds__127-scaled.jpg\",\"datePublished\":\"2025-05-13T14:35:00+00:00\",\"dateModified\":\"2026-03-02T14:41:41+00:00\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\\\/#primaryimage\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/090525OceanWinds__127-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2026\\\/02\\\/090525OceanWinds__127-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#website\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/\",\"name\":\"Windfloat Atlantic\",\"description\":\"Offshore wind energy\",\"publisher\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/windfloat-atlantic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#organization\",\"name\":\"Windfloat Atlantic\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WFA_logo_positivo.svg\",\"contentUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WFA_logo_positivo.svg\",\"width\":167,\"height\":52,\"caption\":\"Windfloat Atlantic\"},\"image\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/person\\\/def3ccdd491df4212cdb4b414f0134fb\",\"name\":\"claudia.barreiro\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eba9e0568cd21abbae6e65a6b1307bba990e80e63a98a612f0c7c0bd26086cd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eba9e0568cd21abbae6e65a6b1307bba990e80e63a98a612f0c7c0bd26086cd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3eba9e0568cd21abbae6e65a6b1307bba990e80e63a98a612f0c7c0bd26086cd?s=96&d=mm&r=g\",\"caption\":\"claudia.barreiro\"},\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/author\\\/claudia-barreiro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic | Windfloat Atlantic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/","og_locale":"pt_PT","og_type":"article","og_title":"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic | Windfloat Atlantic","og_description":"14 de Maio, Viana do Castelo.&nbsp;Ocean Winds \u2014 uma&nbsp;joint&nbsp;venture 50:50 entre a EDP Renov\u00e1veis e a ENGIE, e a principal desenvolvedora do projeto WindFloat Atlantic de 25 MW, o primeiro parque e\u00f3lico offshore semi-submers\u00edvel flutuante do mundo, localizado a aproximadamente 20 quil\u00f4metros da costa de Viana do Castelo \u2014 celebra o quinto anivers\u00e1rio das opera\u00e7\u00f5es [&hellip;]","og_url":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/","og_site_name":"Windfloat Atlantic","article_published_time":"2025-05-13T14:35:00+00:00","article_modified_time":"2026-03-02T14:41:41+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2026\/02\/090525OceanWinds__127-scaled.jpg","type":"image\/jpeg"}],"author":"claudia.barreiro","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"claudia.barreiro","Tempo estimado de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/#article","isPartOf":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/"},"author":{"name":"claudia.barreiro","@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/person\/def3ccdd491df4212cdb4b414f0134fb"},"headline":"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic","datePublished":"2025-05-13T14:35:00+00:00","dateModified":"2026-03-02T14:41:41+00:00","mainEntityOfPage":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/"},"wordCount":957,"commentCount":0,"publisher":{"@id":"https:\/\/windfloat-atlantic.com\/#organization"},"image":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/#primaryimage"},"thumbnailUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2026\/02\/090525OceanWinds__127-scaled.jpg","inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/","url":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/","name":"Ocean Winds comemora 5 anos do parque e\u00f3lico offshore flutuante Windfloat Atlantic | Windfloat Atlantic","isPartOf":{"@id":"https:\/\/windfloat-atlantic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/#primaryimage"},"image":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/#primaryimage"},"thumbnailUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2026\/02\/090525OceanWinds__127-scaled.jpg","datePublished":"2025-05-13T14:35:00+00:00","dateModified":"2026-03-02T14:41:41+00:00","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/ocean-winds-comemora-5-anos-do-parque-eolico-offshore-flutuante-windfloat-atlantic\/#primaryimage","url":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2026\/02\/090525OceanWinds__127-scaled.jpg","contentUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2026\/02\/090525OceanWinds__127-scaled.jpg","width":2560,"height":1707},{"@type":"WebSite","@id":"https:\/\/windfloat-atlantic.com\/#website","url":"https:\/\/windfloat-atlantic.com\/","name":"Windfloat Atlantic","description":"Offshore wind energy","publisher":{"@id":"https:\/\/windfloat-atlantic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/windfloat-atlantic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/windfloat-atlantic.com\/#organization","name":"Windfloat Atlantic","url":"https:\/\/windfloat-atlantic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/logo\/image\/","url":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/07\/WFA_logo_positivo.svg","contentUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/07\/WFA_logo_positivo.svg","width":167,"height":52,"caption":"Windfloat Atlantic"},"image":{"@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/person\/def3ccdd491df4212cdb4b414f0134fb","name":"claudia.barreiro","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/3eba9e0568cd21abbae6e65a6b1307bba990e80e63a98a612f0c7c0bd26086cd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3eba9e0568cd21abbae6e65a6b1307bba990e80e63a98a612f0c7c0bd26086cd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3eba9e0568cd21abbae6e65a6b1307bba990e80e63a98a612f0c7c0bd26086cd?s=96&d=mm&r=g","caption":"claudia.barreiro"},"url":"https:\/\/windfloat-atlantic.com\/pt-pt\/author\/claudia-barreiro\/"}]}},"_links":{"self":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/posts\/2793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/users\/104"}],"replies":[{"embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=2793"}],"version-history":[{"count":4,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/posts\/2793\/revisions"}],"predecessor-version":[{"id":3044,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/posts\/2793\/revisions\/3044"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/media\/2794"}],"wp:attachment":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=2793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=2793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=2793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}