{"id":1603,"date":"2022-12-05T16:33:47","date_gmt":"2022-12-05T16:33:47","guid":{"rendered":"https:\/\/windfloat-atlantic.com\/?p=1603"},"modified":"2023-01-04T09:27:56","modified_gmt":"2023-01-04T09:27:56","slug":"windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional","status":"publish","type":"post","link":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/","title":{"rendered":"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional)"},"content":{"rendered":"\n<p>No dia 21 de novembro, a equipe da WindFloat Atlantic recebeu uma delega\u00e7\u00e3o de profissionais da universidade francesa e do setor de EFP para visitar as nossas instala\u00e7\u00f5es de O&amp;M em Viana do Castelo, Portugal. A visita foi possibilitada pelo apoio \u00e0 coopera\u00e7\u00e3o entre a CIM do Alto Minho (Portugal) e a C\u00e2mara Municipal de Finist\u00e8re (Fran\u00e7a), na organiza\u00e7\u00e3o de visitas a empresas mar\u00edtimas, navais e energ\u00e9ticas em Portugal.<\/p>\n\n\n\n<p>Sendo o projeto WindFloat Atlantic o primeiro parque e\u00f3lico offshore flutuante semi-submers\u00edvel do mundo e o \u00fanico parque e\u00f3lico offshore atualmente em opera\u00e7\u00e3o em Portugal, temos como objetivo sensibilizar e educar sobre os benef\u00edcios das energias renov\u00e1veis e da transi\u00e7\u00e3o energ\u00e9tica, bem como a inova\u00e7\u00e3o tecnol\u00f3gica flutuante.<\/p>\n\n\n\n<p>Embora as condi\u00e7\u00f5es meteorol\u00f3gicas n\u00e3o permitissem uma visita offshore, a delega\u00e7\u00e3o recebeu explica\u00e7\u00f5es em detalhes sobre a hist\u00f3ria, desafios e singularidade do projeto WindFloat Atlantic realizado pela nossa equipe O&amp;M e visitou a base O&amp;M e o centro de controle remoto do parque e\u00f3lico.<\/p>\n\n\n\n<p>O grupo foi composto por Juliette Corbill\u00e9 (diretora de coopera\u00e7\u00e3o para o Conselho do Condado de Finist\u00e8re e conven\u00e7\u00e3o de coopera\u00e7\u00e3o CIM Alto Minho), Josselin Chesnel (gestor de projetos de mobilidade internacional para o cons\u00f3rcio), Christophe Le Bras (gestor de forma\u00e7\u00e3o e instrutor em comercializa\u00e7\u00e3o de energias na P\u00f4le Formation UIMM Bretagne), Brigitte Andrieux (professora de ingl\u00eas no Institut de technologie \u2013 Universit\u00e9 de Bretagne occidentale) e Alban Le Trionnaire (estudante em ind\u00fastria eletrot\u00e9cnica na P\u00f4le Formation UIMM Bretagne); todos os membros de um cons\u00f3rcio de institui\u00e7\u00f5es de ensino superior e de EFP, compostas por: P\u00f4le Formation UIMM Bretagne (Centro de Forma\u00e7\u00e3o Profissional Brittany da UIMM \u2013 Metalurgia Ind\u00fastria e Federa\u00e7\u00e3o do Com\u00e9rcio), o IUT Brest-Morlaix (Universidade da Bretanha Ocidental e o seu Instituto de Tecnologia Brest-Morlaix) e CINav (Campus das Ind\u00fastrias Navais).<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"473\" data-id=\"1638\" src=\"\/wp-content\/uploads\/2022\/12\/French-unis.1-min-1024x473.jpg\" alt=\"\" class=\"wp-image-1638\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-1024x473.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-300x139.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-768x355.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-1536x709.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-2048x946.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-id=\"1616\" src=\"\/wp-content\/uploads\/2022\/12\/French-unis.2-1-1024x768.jpg\" alt=\"\" class=\"wp-image-1616\" srcset=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.2-1-1024x768.jpg 1024w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.2-1-300x225.jpg 300w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.2-1-768x576.jpg 768w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.2-1-1536x1152.jpg 1536w, https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.2-1.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>No dia 21 de novembro, a equipe da WindFloat Atlantic recebeu uma delega\u00e7\u00e3o de profissionais da universidade francesa e do setor de EFP para visitar as nossas instala\u00e7\u00f5es de O&amp;M em Viana do Castelo, Portugal. A visita foi possibilitada pelo apoio \u00e0 coopera\u00e7\u00e3o entre a CIM do Alto Minho (Portugal) e a C\u00e2mara Municipal de [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":1638,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[12],"tags":[],"class_list":["post-1603","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sem-categoria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional) | Windfloat Atlantic<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional) | Windfloat Atlantic\" \/>\n<meta property=\"og:description\" content=\"No dia 21 de novembro, a equipe da WindFloat Atlantic recebeu uma delega\u00e7\u00e3o de profissionais da universidade francesa e do setor de EFP para visitar as nossas instala\u00e7\u00f5es de O&amp;M em Viana do Castelo, Portugal. A visita foi possibilitada pelo apoio \u00e0 coopera\u00e7\u00e3o entre a CIM do Alto Minho (Portugal) e a C\u00e2mara Municipal de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/\" \/>\n<meta property=\"og:site_name\" content=\"Windfloat Atlantic\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-05T16:33:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-04T09:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1182\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kelly\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kelly\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/\"},\"author\":{\"name\":\"Kelly\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/person\\\/0733b6f138042b9640d126fd22a1423b\"},\"headline\":\"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional)\",\"datePublished\":\"2022-12-05T16:33:47+00:00\",\"dateModified\":\"2023-01-04T09:27:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/French-unis.1-min-scaled.jpg\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/\",\"name\":\"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional) | Windfloat Atlantic\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/French-unis.1-min-scaled.jpg\",\"datePublished\":\"2022-12-05T16:33:47+00:00\",\"dateModified\":\"2023-01-04T09:27:56+00:00\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\\\/#primaryimage\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/French-unis.1-min-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/French-unis.1-min-scaled.jpg\",\"width\":2560,\"height\":1182},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#website\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/\",\"name\":\"Windfloat Atlantic\",\"description\":\"Offshore wind energy\",\"publisher\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/windfloat-atlantic.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#organization\",\"name\":\"Windfloat Atlantic\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WFA_logo_positivo.svg\",\"contentUrl\":\"https:\\\/\\\/windfloat-atlantic.com\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/WFA_logo_positivo.svg\",\"width\":167,\"height\":52,\"caption\":\"Windfloat Atlantic\"},\"image\":{\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/windfloat-atlantic.com\\\/#\\\/schema\\\/person\\\/0733b6f138042b9640d126fd22a1423b\",\"name\":\"Kelly\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a5c50e1bd977db4ce4206518995657691b97dd7f98740159a51d42c1b1e7c80?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a5c50e1bd977db4ce4206518995657691b97dd7f98740159a51d42c1b1e7c80?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a5c50e1bd977db4ce4206518995657691b97dd7f98740159a51d42c1b1e7c80?s=96&d=mm&r=g\",\"caption\":\"Kelly\"},\"url\":\"https:\\\/\\\/windfloat-atlantic.com\\\/pt-pt\\\/author\\\/kelly\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional) | Windfloat Atlantic","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/","og_locale":"pt_PT","og_type":"article","og_title":"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional) | Windfloat Atlantic","og_description":"No dia 21 de novembro, a equipe da WindFloat Atlantic recebeu uma delega\u00e7\u00e3o de profissionais da universidade francesa e do setor de EFP para visitar as nossas instala\u00e7\u00f5es de O&amp;M em Viana do Castelo, Portugal. A visita foi possibilitada pelo apoio \u00e0 coopera\u00e7\u00e3o entre a CIM do Alto Minho (Portugal) e a C\u00e2mara Municipal de [&hellip;]","og_url":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/","og_site_name":"Windfloat Atlantic","article_published_time":"2022-12-05T16:33:47+00:00","article_modified_time":"2023-01-04T09:27:56+00:00","og_image":[{"width":2560,"height":1182,"url":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-scaled.jpg","type":"image\/jpeg"}],"author":"Kelly","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Kelly","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/#article","isPartOf":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/"},"author":{"name":"Kelly","@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/person\/0733b6f138042b9640d126fd22a1423b"},"headline":"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional)","datePublished":"2022-12-05T16:33:47+00:00","dateModified":"2023-01-04T09:27:56+00:00","mainEntityOfPage":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/windfloat-atlantic.com\/#organization"},"image":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/#primaryimage"},"thumbnailUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-scaled.jpg","inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/","url":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/","name":"WindFloat Atlantic deu as boas-vindas aos profissionais da ind\u00fastria da Universidade e da EFP francesas (Educa\u00e7\u00e3o e Forma\u00e7\u00e3o Profissional) | Windfloat Atlantic","isPartOf":{"@id":"https:\/\/windfloat-atlantic.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/#primaryimage"},"image":{"@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/#primaryimage"},"thumbnailUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-scaled.jpg","datePublished":"2022-12-05T16:33:47+00:00","dateModified":"2023-01-04T09:27:56+00:00","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/windfloat-atlantic.com\/pt-pt\/windfloat-altantic-deu-as-boas-vindas-aos-profissionais-da-industria-da-universidade-e-da-efp-francesas-educacao-e-formacao-profissional\/#primaryimage","url":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-scaled.jpg","contentUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/12\/French-unis.1-min-scaled.jpg","width":2560,"height":1182},{"@type":"WebSite","@id":"https:\/\/windfloat-atlantic.com\/#website","url":"https:\/\/windfloat-atlantic.com\/","name":"Windfloat Atlantic","description":"Offshore wind energy","publisher":{"@id":"https:\/\/windfloat-atlantic.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/windfloat-atlantic.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/windfloat-atlantic.com\/#organization","name":"Windfloat Atlantic","url":"https:\/\/windfloat-atlantic.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/logo\/image\/","url":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/07\/WFA_logo_positivo.svg","contentUrl":"https:\/\/windfloat-atlantic.com\/wp-content\/uploads\/2022\/07\/WFA_logo_positivo.svg","width":167,"height":52,"caption":"Windfloat Atlantic"},"image":{"@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/windfloat-atlantic.com\/#\/schema\/person\/0733b6f138042b9640d126fd22a1423b","name":"Kelly","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/3a5c50e1bd977db4ce4206518995657691b97dd7f98740159a51d42c1b1e7c80?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3a5c50e1bd977db4ce4206518995657691b97dd7f98740159a51d42c1b1e7c80?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a5c50e1bd977db4ce4206518995657691b97dd7f98740159a51d42c1b1e7c80?s=96&d=mm&r=g","caption":"Kelly"},"url":"https:\/\/windfloat-atlantic.com\/pt-pt\/author\/kelly\/"}]}},"_links":{"self":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/posts\/1603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=1603"}],"version-history":[{"count":0,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/posts\/1603\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/media\/1638"}],"wp:attachment":[{"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=1603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=1603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/windfloat-atlantic.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=1603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}